{"id":12973,"date":"2026-04-27T18:45:29","date_gmt":"2026-04-27T16:45:29","guid":{"rendered":"https:\/\/ehartner.com\/?post_type=product&#038;p=12973"},"modified":"2026-06-29T12:10:47","modified_gmt":"2026-06-29T10:10:47","slug":"m12-winkeldose-polzahl-8-ungeschirmt-am-kabel-angespritzt-ip69k-ul-2238-pur-schwarz-8-x-025-mm%c2%b2-5-m","status":"publish","type":"product","link":"https:\/\/ehartner.com\/en\/sensorstecker-umspritzt\/m12-winkeldose-polzahl-8-ungeschirmt-am-kabel-angespritzt-ip69k-ul-2238-pur-schwarz-8-x-025-mm%c2%b2-5-m\/","title":{"rendered":"M12 Winkeldose, Polzahl: 8, ungeschirmt, am Kabel angespritzt, IP69K, UL 2238, PUR, schwarz, 8 x 0,25 mm\u00b2, 5 m"},"content":{"rendered":"<p>Der M12 Sensor-\/Aktorsteckverbinder 77 3434 0000 50708 0500 von Binder kombiniert 8-polige Ausf\u00fchrung mit 5 m Kabell\u00e4nge und h\u00f6chstem Schutzgrad IP69K. Die ungeschirmte Bauweise ist f\u00fcr Standard-Automatisierungsaufgaben ohne besondere EMV-Anforderungen ausgelegt.<\/p>\n<p>Das fest angespritzte, 5 m lange Kabel mit schwarzem PUR-Mantel bietet einen Leiterquerschnitt von 8 x 0,25 mm\u00b2. Die UL 2238 Zertifizierung erf\u00fcllt internationale Sicherheitsstandards. Die Schutzart IP69K bietet maximalen Schutz gegen Eindringen von Staub sowie gegen Hochdruck- und Dampfstrahlreinigung bis 100 bar und 80\u00b0C.<\/p>\n<p>Die Winkelbauform erm\u00f6glicht platzsparende Installation in beengten Maschinenumgebungen. Die M12-Schraubverriegelung sichert eine zuverl\u00e4ssige, vibrationsbest\u00e4ndige Verbindung. Das Produkt der Binder Serie 765\/763 ist f\u00fcr anspruchsvollste Industrieumgebungen konzipiert.<\/p>\n<p>Typische Einsatzbereiche sind Nahrungsmittelverarbeitung, chemische Industrie, Reinigungsstationen und \u00fcberall dort, wo aggressive Reinigungsverfahren zum Einsatz kommen. Die l\u00e4ngere Kabell\u00e4nge bietet mehr Flexibilit\u00e4t bei der Anlagenplanung.<\/p>","protected":false},"excerpt":{"rendered":"<p>M12 Winkeldose mit 8 Polen, ungeschirmt, Schutzart IP69K. Kabell\u00e4nge 5 m mit PUR-Mantel, schwarz, UL 2238 zertifiziert. Schraubverriegelung M12, Leiterquerschnitt 8 x 0,25 mm\u00b2.<\/p>","protected":false},"featured_media":31588,"template":"","meta":[],"product_brand":[26],"product_cat":[1518,1979,1974,1617],"product_tag":[],"class_list":["post-12973","product","type-product","status-publish","has-post-thumbnail","product_brand-binder","product_cat-sensorstecker","product_cat-sensorstecker-umspritzt","product_cat-steckverbinder-umspritzt","product_cat-binder-sensorik-verbindung","first","instock","taxable","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/product\/12973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/product\/12973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/media\/31588"}],"wp:attachment":[{"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/media?parent=12973"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/product_brand?post=12973"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/product_cat?post=12973"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ehartner.com\/en\/wp-json\/wp\/v2\/product_tag?post=12973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}